{"id":8856,"date":"2022-02-18T10:19:09","date_gmt":"2022-02-18T09:19:09","guid":{"rendered":"https:\/\/clouding.io\/blog\/?p=8856"},"modified":"2024-02-28T11:43:52","modified_gmt":"2024-02-28T10:43:52","slug":"kit-digital-agente-digitalizador","status":"publish","type":"post","link":"https:\/\/clouding.io\/blog\/kit-digital-agente-digitalizador\/","title":{"rendered":"El Kit Digital permite convertirte en Agente Digitalizador"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><strong>En qu\u00e9 consiste el Kit Digital<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El Gobierno de Espa\u00f1a, a trav\u00e9s del Ministerio de Asuntos Econ\u00f3micos y Transformaci\u00f3n Digital, ha lanzado el <strong>Programa Kit Digital o <\/strong><em><strong>Digital Toolkit<\/strong>.<\/em> Con esta iniciativa peque\u00f1as empresas, microempresas y trabajadores aut\u00f3nomos de cualquier sector pueden solicitar una ayuda p\u00fablica destinada la transformaci\u00f3n digital de su negocio. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas ayudas p\u00fablicas, que pretenden revitalizar el tejido empresarial espa\u00f1ol y que provienen de los fondos Next Generation de la Uni\u00f3n Europea, re\u00fanen una <strong>dotaci\u00f3n de 3.067 millones de euros<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las empresas que se beneficien del Kit Digital podr\u00e1 hacerse con nuevas herramientas digitales, desarrollar su potencial y alcanzar la madurez digital.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube aligncenter wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Kit Digital\" width=\"900\" height=\"506\" src=\"https:\/\/www.youtube.com\/embed\/fI_Y5W25hPs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\">Video presentaci\u00f3n del Kit Digital<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Las empresas potenciales beneficiarias del Kit Digital se dividen en tres segmentos dependiendo del n\u00famero de empleados:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Un primer segmento compuesto por peque\u00f1as empresas de<strong> m\u00e1s&nbsp;de 10 y hasta 49 empleados<\/strong>.<\/li>\n\n\n\n<li>Un segundo tramo de peque\u00f1as empresas o microempresas de&nbsp;<strong>entre 3 y hasta 10 empleados<\/strong>.<\/li>\n\n\n\n<li>Un tercer segmento de&nbsp;<strong>microempresas de menos de 3 empleados<\/strong>&nbsp;o <strong>trabajadores aut\u00f3nomos<\/strong>.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Pasos a seguir para solicitar el <em>Digital Toolkit<\/em><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">En esta <a rel=\"noreferrer noopener\" href=\"https:\/\/acelerapyme.gob.es\/sites\/acelerapyme\/files\/2022-01\/Kit_Digital_Gui%CC%81a_pymes_13-01-22.pdf\" target=\"_blank\">gu\u00eda r\u00e1pida<\/a> se pueden consultar los requisitos necesarios para solicitar la ayuda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proceso de obtenci\u00f3n del Kit Digital se gestiona a trav\u00e9s de gestiona a trav\u00e9s de <a rel=\"noreferrer noopener\" href=\"https:\/\/www.acelerapyme.gob.es\/\" target=\"_blank\">AceleraPyme<\/a>, una plataforma cuya misi\u00f3n es la de facilitar e impulsar la transformaci\u00f3n digital de las empresas espa\u00f1olas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las que hayan comprobado que son candidatas elegibles,  han de seguir los siguientes pasos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Acceder a&nbsp;<strong>AceleraPyme<\/strong>&nbsp;y<strong>&nbsp;<a href=\"https:\/\/www.acelerapyme.gob.es\/registro-pyme\">registrar la empresa mediante un formulario online<\/a><\/strong>.<\/li>\n\n\n\n<li><strong>Realizar el Test de Diagn\u00f3stico Digital<\/strong>, tambi\u00e9n conocido como test de nivel de madurez digital. Este test consta de preguntas como la conexi\u00f3n a internet o las RRSS.<\/li>\n\n\n\n<li>Una vez hecho esto, las potenciales beneficiarias recibir\u00e1n un <strong>bono digital con una asignaci\u00f3n econ\u00f3mica concreta de hasta 12.000 euros<\/strong>, que pueden invertir en una o varias de las siguientes <strong>categor\u00edas de servicios digitales<\/strong> ofrecidos por el <em>marketplace <\/em>de los llamados Agentes Digitalizadores dentro de un <strong>cat\u00e1logo cerrado<\/strong>:<br><br>\n<ul class=\"wp-block-list\">\n<li>Sitio web y presencia en internet<\/li>\n\n\n\n<li>Comercio electr\u00f3nico<\/li>\n\n\n\n<li>Inteligencia empresarial y anal\u00edtica<\/li>\n\n\n\n<li>Gesti\u00f3n de clientes<\/li>\n\n\n\n<li>Gesti\u00f3n de Redes Sociales<\/li>\n\n\n\n<li>Servicios y Herramientas de Oficina Virtual<\/li>\n\n\n\n<li>Gesti\u00f3n de procesos<\/li>\n\n\n\n<li>Factura electr\u00f3nica<\/li>\n\n\n\n<li>Ciberseguridad<\/li>\n\n\n\n<li>Comunicaciones seguras<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Las empresas que reciban el bono disponen de un <strong>plazo de seis meses para usarlo<\/strong> en hasta cinco servicios digitales, de un a\u00f1o de duraci\u00f3n cada uno de ellos.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>C\u00f3mo hacerse Agente Digitalizador<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Esta oportunidad del Kit Digital abre su abanico no s\u00f3lo a sus potenciales beneficiarias sino tambi\u00e9n en las empresas interesadas en hacerse Agentes Digitalizadores<\/strong>, que son las que ofrecer\u00e1n sus recursos digitales y acompa\u00f1ar\u00e1n a las empresas beneficiadas por la ayuda en sus caminos de conversi\u00f3n digital. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las que quieran aparecer en el marketplace de AceleraPymes como Agentes Digitalizadores tienen que inscribirse en la <a rel=\"noreferrer noopener\" href=\"https:\/\/sede.red.gob.es\/es\/procedimientos\/anuncio-de-adhesion-de-agentes-digitalizadores-al-programa-de-ayudas-para-la\" target=\"_blank\">sede electr\u00f3nica de Red.es<\/a>, rellenar el formulario y especificar cu\u00e1l es la soluci\u00f3n digital que ofrecen dentro de las que hemos mencionado m\u00e1s arriba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los <strong>requisitos necesarios para hacerse Agente Digitalizador <\/strong>son los siguientes:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No estar considerada como empresa en crisis. Por este requisito se ver\u00e1n afectadas muchas empresas a causa de las consecuencias econ\u00f3micas derivadas de la pandemia.<\/li>\n\n\n\n<li>Para las peque\u00f1as empresas y microempresas, haber obtenido una facturaci\u00f3n anual de al menos 100.000 euros en alguno de los dos ejercicios anteriores a la solicitud, o 50.000 euros en el a\u00f1o anterior. Para los aut\u00f3nomos, 70.000 euros de facturaci\u00f3n en alguno de los dos ejercicios anteriores, o 35.000 euros en el a\u00f1o anterior.<\/li>\n\n\n\n<li>Estar al corriente de las obligaciones con Hacienda y con la Seguridad Social.<\/li>\n\n\n\n<li>Tener una antig\u00fcedad m\u00ednima de dos a\u00f1os.<\/li>\n\n\n\n<li>Tener el domicilio fiscal en la Uni\u00f3n Europea.<\/li>\n\n\n\n<li>Comprometerse a generar en Espa\u00f1a los puestos de trabajo que sean necesario para el desarrollo de las actividades digitales.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las empresas que consigan cualificarse, aparecer\u00e1n incluidas en el cat\u00e1logo de Agentes Digitalizadores y, cuando sean elegidas por los beneficiarias, firmar\u00e1n<strong> acuerdos de colaboraci\u00f3n con las empresas que han obtenido el bono digital<\/strong> y las orientar\u00e1n y guiar\u00e1n en sus procesos de transformaci\u00f3n digital a trav\u00e9s de uno o varios de los servicios descritos m\u00e1s arriba por el plazo de un a\u00f1o.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Plazos a tener en cuenta sobre el Kit Digital<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El d\u00eda 11 de enero de 2022 se abri\u00f3 el plazo para presentar la solicitud para incorporarse al marketplace como Agente Digitalizador<\/strong> presentando soluciones digitales concretas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El plan de ayudas p\u00fablicas del Kit Digital se desarrollar\u00e1 a trav\u00e9s de tres convocatorias:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>El d\u00eda 26 de febrero de 2022<\/strong> se abrir\u00e1 el plazo para la primera convocatoria de ayudas, destinadas a pymes de 10 a 49 empleados.<\/li>\n\n\n\n<li><strong>A lo largo de esta a\u00f1o 2022 <\/strong>se abrir\u00e1n otras dos convocatorias para las dos categor\u00edas restantes, destinadas a peque\u00f1as empresas, microempresas y trabajadores aut\u00f3nomos.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Conclusiones sobre el Kit Digital<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El Kit Digital pretende ser un revulsivo para las pymes y aut\u00f3nomos espa\u00f1oles, proporcion\u00e1ndoles un soporte en la carrera digital e impulsando su inserci\u00f3n en nuevos mercados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En Clouding nos gusta aportar soluciones y ayudar nuestros clientes a expandirse y alcanzar todo su potencial.<\/strong> Esperamos que esta informaci\u00f3n haya sido de utilidad para ti y, si te consideras un candidato elegible, te animamos a solicitar tu candidatura como Agente Digitalizar para ampliar tus oportunidades de negocio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00a1\u00danete al movimiento de la transformaci\u00f3n digital!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Kit Digital son una serie de ayudas p\u00fablicas para la transformaci\u00f3n digital de pymes y microempresas con la colaboraci\u00f3n de los Agentes Digitalizadores.<\/p>\n","protected":false},"author":2,"featured_media":9967,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[88,3],"tags":[5582,5581],"yst_prominent_words":[5512,5483,5578,1341,5580,763,5517,5519,5518,5570,5513,5475,5474,5535,5521,5520,5579,5522,1333,2209],"class_list":["post-8856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-uncategorized-ca","tag-agente-digitalizador","tag-kit-digital"],"acf":[],"_links":{"self":[{"href":"https:\/\/clouding.io\/blog\/wp-json\/wp\/v2\/posts\/8856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clouding.io\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/clouding.io\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/clouding.io\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/clouding.io\/blog\/wp-json\/wp\/v2\/comments?post=8856"}],"version-history":[{"count":37,"href":"https:\/\/clouding.io\/blog\/wp-json\/wp\/v2\/posts\/8856\/revisions"}],"predecessor-version":[{"id":9970,"href":"https:\/\/clouding.io\/blog\/wp-json\/wp\/v2\/posts\/8856\/revisions\/9970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/clouding.io\/blog\/wp-json\/wp\/v2\/media\/9967"}],"wp:attachment":[{"href":"https:\/\/clouding.io\/blog\/wp-json\/wp\/v2\/media?parent=8856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/clouding.io\/blog\/wp-json\/wp\/v2\/categories?post=8856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clouding.io\/blog\/wp-json\/wp\/v2\/tags?post=8856"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/clouding.io\/blog\/wp-json\/wp\/v2\/yst_prominent_words?post=8856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}